{"id":11906,"date":"2019-04-16T00:00:00","date_gmt":"2021-06-28T14:44:06","guid":{"rendered":"https:\/\/arquiconsult.com\/?p=11906"},"modified":"2026-01-14T11:15:59","modified_gmt":"2026-01-14T11:15:59","slug":"contratar-mais-50-pessoas","status":"publish","type":"post","link":"https:\/\/arquiconsult.com\/es\/contratar-mais-50-pessoas\/","title":{"rendered":"TECNOL\u00d3GICA ARQUICONSULT VAI CONTRATAR MAIS 50 PESSOAS"},"content":{"rendered":"<h4 style=\"text-align: left;\">A <a href=\"https:\/\/arquiconsult.com\/\">empresa<\/a> de consultoria de sistemas de informa\u00e7\u00e3o, com sede em Matosinhos e escrit\u00f3rios em Lisboa, Barcelona e Luanda, gera no exterior mais de um ter\u00e7o da sua fatura\u00e7\u00e3o de 10 milh\u00f5es de euros, emprega 140 pessoas e pretende contratar mais 50 este ano.<\/h4>\n<hr id=\"system-readmore\" \/>\n<p style=\"text-align: left;\"><strong>A empresa de consultoria de sistemas de informa\u00e7\u00e3o, com sede em Matosinhos e escrit\u00f3rios em Lisboa, <a href=\"https:\/\/goo.gl\/maps\/PKM1M2BQgSZn94Ps5\" target=\"_blank\" rel=\"noopener\">Barcelona<\/a> e <a href=\"https:\/\/goo.gl\/maps\/Qi1PAfr7LF9p1jmm8\" target=\"_blank\" rel=\"noopener\">Luanda<\/a>, gera no exterior mais de um ter\u00e7o da sua fatura\u00e7\u00e3o de 10 milh\u00f5es de euros, emprega 140 pessoas e pretende contratar mais 50 este ano.<\/strong><\/p>\n<p style=\"text-align: left;\">Na \u00faltima d\u00e9cada, a tecnol\u00f3gica Arquiconsult multiplicou por quatro a fatura\u00e7\u00e3o, de 2,5 milh\u00f5es em 2008 para 10 milh\u00f5es de euros no ano passado, e mais do que triplicou o efetivo para 145 pessoas &#8211; 80 em Lisboa, 45 em Matosinhos, 12 em Espanha e oito em Angola, e pretende contratar mais 50 este ano.<\/p>\n<p style=\"text-align: left;\">Um crescimento bastante impulsionado pela internacionaliza\u00e7\u00e3o da empresa, nos \u00faltimos cinco anos, com a abertura de escrit\u00f3rios em Barcelona, Madrid e Luanda, com os mercados externos a valerem j\u00e1 35% do volume de neg\u00f3cios, garante Rui Santos, CEO desta empresa de consultoria especializada na implementa\u00e7\u00e3o de sistemas de gest\u00e3o, colabora\u00e7\u00e3o e &#8220;business intelligence&#8221;.<\/p>\n<p style=\"text-align: left;\">&#8220;Em Portugal, temos j\u00e1 uma dimens\u00e3o que n\u00e3o nos permite crescer muito mais, por isso, tanto o escrit\u00f3rio de Luanda como o de Barcelona s\u00e3o para ser expandidos e teremos de procurar novas zonas geogr\u00e1ficas onde possamos crescer&#8221;, avan\u00e7a Rui Santos, que pretende &#8220;manter o ritmo de crescimento de dois d\u00edgitos&#8221; na fatura\u00e7\u00e3o, chegando aos 11 milh\u00f5es de euros este ano, e &#8220;contratar 50 profissionais durante o ano de 2019&#8221;.<\/p>\n<p style=\"text-align: left;\">&#8220;Os 50 colaboradores a contratar s\u00e3o todos para Portugal &#8211; jovens licenciados em ci\u00eancias s\u00f3cio-econ\u00f3micas e tecnol\u00f3gicas, para ocuparem fun\u00e7\u00f5es de consultores funcionais e consultores t\u00e9cnicos&#8221;, detalhou fonte oficial da empresa, em declara\u00e7\u00f5es ao Neg\u00f3cios.<\/p>\n<p style=\"text-align: left;\">&#8220;Gold Certified Partner&#8221; da Microsoft, as solu\u00e7\u00f5es da Arquiconsult servem \u00e1reas de atua\u00e7\u00e3o empresarial que v\u00e3o do retalho e com\u00e9rcio \u00e0 hotelaria, log\u00edstica e transportes, recursos humanos, navega\u00e7\u00e3o, abrangendo, ainda, entre outros, os setores da constru\u00e7\u00e3o e gest\u00e3o de espa\u00e7o, ambiente e ind\u00fastria.<\/p>\n<p style=\"font-size: 14px; text-align: left;\">Jornal de Neg\u00f3cios. Neves, Rui. 3 abril 2019. Tecnol\u00f3gica Arquiconsult vai contratar mais 50 pessoas. Dispon\u00edvel em: <a href=\"https:\/\/www.jornaldenegocios.pt\/empresas\/tecnologias\/detalhe\/tecnologica-arquiconsult-vai-contratar-mais-50-pessoas\" target=\"_bank\" rel=\"noopener\">https:\/\/www.jornaldenegocios.pt\/empresas\/tecnologias\/detalhe\/tecnologica-arquiconsult-vai-contratar-mais-50-pessoas<\/a><\/p>\n<!--themify_builder_content-->\n<div id=\"themify_builder_content-11906\" data-postid=\"11906\" class=\"themify_builder_content themify_builder_content-11906 themify_builder tf_clear\">\n    <\/div>\n<!--\/themify_builder_content-->\n","protected":false},"excerpt":{"rendered":"<p>A empresa de consultoria de sistemas de informa\u00e7\u00e3o, com sede em Matosinhos e escrit\u00f3rios em Lisboa, Barcelona e Luanda, gera no exterior mais de um ter\u00e7o da sua fatura\u00e7\u00e3o de 10 milh\u00f5es de euros, emprega 140 pessoas e pretende contratar mais 50 este ano. A empresa de consultoria de sistemas de informa\u00e7\u00e3o, com sede em [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1126],"tags":[2046,1511,1864,1512,2445],"acf":[],"_links":{"self":[{"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/posts\/11906"}],"collection":[{"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/comments?post=11906"}],"version-history":[{"count":2,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/posts\/11906\/revisions"}],"predecessor-version":[{"id":121404,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/posts\/11906\/revisions\/121404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/media\/29604"}],"wp:attachment":[{"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/media?parent=11906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/categories?post=11906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/tags?post=11906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}