{"id":12364,"date":"2020-09-02T00:00:00","date_gmt":"2021-06-28T14:52:43","guid":{"rendered":"https:\/\/arquiconsult.com\/?p=12364"},"modified":"2026-01-12T11:21:08","modified_gmt":"2026-01-12T11:21:08","slug":"klog-transport-solutions-press-release","status":"publish","type":"post","link":"https:\/\/arquiconsult.com\/es\/klog-transport-solutions-press-release\/","title":{"rendered":"KLOG TRANSPORT SOLUTIONS &#8211; PRESS RELEASE"},"content":{"rendered":"<h4 style=\"text-align: left;\">A <a href=\"https:\/\/www.klog.pt\/transport\/\" target=\"_blank\" rel=\"noopener\">Klog Transport Solutions<\/a>, empresa que opera no setor do transporte por via terrestre, transporte de mercadorias perigosas, contentores e carga em geral, com actividade nacional e internacional, tem vindo sempre a apostar em tecnologia que permita uma resposta adequada \u00e0s suas necessidades.<\/h4>\n<hr id=\"system-readmore\" \/>\n<h4 style=\"text-align: left;\"><strong>Ultrapassar a crise e projetar o futuro com novos projetos<\/strong><\/h4>\n<p style=\"text-align: left;\">A Klog Transport Solutions, empresa que opera no setor do transporte por via terrestre, transporte de mercadorias perigosas, contentores e carga em geral, foi fundada em 2018 pelos s\u00f3cios da KLOG Logistics Solutions.<\/p>\n<p style=\"text-align: left;\">Com actividade nacional e internacional, a empresa tem vindo sempre a apostar em tecnologia que permita uma resposta adequada \u00e0s suas necessidades. O ERP Dynamics 365 Business Central <a href=\"https:\/\/arquiconsult.com\/transporte-e-logistica\/\">Navitrans<\/a>, em liga\u00e7\u00e3o com a solu\u00e7\u00e3o OBC (On Board Computer), sistema de telem\u00e1tica e navega\u00e7\u00e3o com GPS profissional para cami\u00f5es, com medi\u00e7\u00e3o cont\u00ednua da performance da condu\u00e7\u00e3o e gest\u00e3o da frota, \u00e9 um bom exemplo da utiliza\u00e7\u00e3o de uma ferramenta global de gest\u00e3o que acrescenta valor ao desempenho da empresa e que garante uma gest\u00e3o mais eficiente de toda a frota, com mais produtividade e menos meios.<\/p>\n<p style=\"text-align: left;\">Durante o per\u00edodo de confinamento a que o pa\u00eds esteve sujeito, a KLOG, dada a diminui\u00e7\u00e3o evidente do volume de carga e ao encerramento dos seus principais clientes, viu-se obrigada a recorrer ao layoff total nos meses de abril e maio. Durante este per\u00edodo de encerramento, a KLOG Transportes continuou a assegurar as entregas B2B e B2C em todo o territ\u00f3rio nacional atrav\u00e9s da rede de distribui\u00e7\u00e3o nacional da KLOG Logistics. A partir do m\u00eas de junho, com a retoma gradual da atividade, a empresa passou a layoff parcial.<\/p>\n<p style=\"text-align: left;\">Nesta situa\u00e7\u00e3o particular de layoff, o Dynamics Navitrans foi de grande utilidade pois permitiu gerir de uma forma autom\u00e1tica os processamentos salariais, garantindo o cumprimento de todos os procedimentos legais exigidos para ambas as situa\u00e7\u00f5es, total e parcial.<\/p>\n<p style=\"text-align: left;\">Para o futuro mais pr\u00f3ximo, a empresa pretende afirmar a marca no mercado internacional dos transportes rodovi\u00e1rios, com especial enfoque no mercado ib\u00e9rico. Para isso, a KLOG tem vindo a investir em equipamento para carga geral, intermodal, transporte em temperatura controlada e equipamento especial, nomeadamente para transporte duo-trailler, sendo este \u00faltimo um projeto piloto com IMT. No imediato, a muito curto prazo, a KLOG vai iniciar a sua atividade para os mercados do MAGHREB.<\/p>\n<div class=\"jumbotron jumbotron-primary\">\n<h3 style=\"text-align: left;\">Descubra mais sobre a solu\u00e7\u00e3o Navitrans<\/h3>\n<p style=\"text-align: left;\"><a class=\"btn btn-primary btn-lg\" href=\"https:\/\/arquiconsult.com\/transporte-e-logistica\/\" target=\"_blank\" rel=\"noopener\">Saber Mais<\/a><\/p>\n<\/div>\n<!--themify_builder_content-->\n<div id=\"themify_builder_content-12364\" data-postid=\"12364\" class=\"themify_builder_content themify_builder_content-12364 themify_builder tf_clear\">\n    <\/div>\n<!--\/themify_builder_content-->\n","protected":false},"excerpt":{"rendered":"<p>A Klog Transport Solutions, empresa que opera no setor do transporte por via terrestre, transporte de mercadorias perigosas, contentores e carga em geral, com actividade nacional e internacional, tem vindo sempre a apostar em tecnologia que permita uma resposta adequada \u00e0s suas necessidades. Ultrapassar a crise e projetar o futuro com novos projetos A Klog [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2701],"tags":[1741,1655,1413],"acf":[],"_links":{"self":[{"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/posts\/12364"}],"collection":[{"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/comments?post=12364"}],"version-history":[{"count":1,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/posts\/12364\/revisions"}],"predecessor-version":[{"id":121237,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/posts\/12364\/revisions\/121237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/media\/29905"}],"wp:attachment":[{"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/media?parent=12364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/categories?post=12364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arquiconsult.com\/es\/wp-json\/wp\/v2\/tags?post=12364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}